﻿{"id":78015,"date":"2022-09-23T10:42:05","date_gmt":"2022-09-23T08:42:05","guid":{"rendered":"https:\/\/www.anygivensunday.it\/home\/?p=78015"},"modified":"2022-09-23T11:48:51","modified_gmt":"2022-09-23T09:48:51","slug":"massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante","status":"publish","type":"post","link":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/","title":{"rendered":"Massimo Giagnorio e la Femminile Molfetta: &#8220;Avventura appassionante&#8221;"},"content":{"rendered":"<p>Domenica la sua \u201cprima\u201d da presidente a capo della <strong>Femminile Molfetta<\/strong> in Serie A femminile. Un\u2019altra importantissima tappa di un cammino che, per <strong>Massimo Giagnorio<\/strong>, \u00e8 stato sempre legatissimo allo sport, sia per quanto riguarda l\u2019impresa che dal 1986 porta avanti insieme al fratello \u2013 la <a href=\"https:\/\/www.sportimpiantigicoma.it\/\">Sport Impianti<\/a> di San Nicandro al Garganico, fondata da pap\u00e0 Gennaro \u2013 sia per quanto riguarda il suo passato da calciatore, tanto brillante quanto sfortunato a causa dei numerosi infortuni, anche di grave entit\u00e0, che ne hanno condizionato il salto nella categoria dei professionisti.<br \/>\n\u201cAmo il calcio e l\u2019ho praticato sin da bambino nelle giovanili del Foggia, prima di iniziare a girare tutta Italia: Voghera, Vercelli, Perugia e poi San Salvo in Abruzzo, tra le altre esperienze. Ero un trequartista di buona prospettiva, ma ben presto \u2013 a soli 25 anni \u2013 ho deciso di smettere. Tra lesioni ai menischi, rottura di crociato e tendine d\u2019Achille e cartilagini completamente consumate, era pi\u00f9 il tempo che trascorrevo in ospedale che sul campo. Era diventato un sacrificio, non riuscivo pi\u00f9 a divertirmi\u201d.<\/p>\n<p>Ma l&#8217;attivit\u00e0 agonistica, seppur in altre forme, \u00e8 rimasto sempre parte integrante della sua vita grazie alla Sport Impianti. Parliamo di un\u2019azienda leader in Italia, che ha realizzato interventi Out Stadio Marcantonio Bentegodi Verona, Out Mapei Stadium Reggio Emilia, Centro Sportivo Giacinto Facchetti e, in collaborazione con la Flex Grass Costruction, si \u00e8 occupata dei lavori di realizzazione dei campi Appiano Gentile F.C. Internazionale Milano.<br \/>\n\u201cPartendo dall\u2019azienda edile creata da mio padre, io e mio fratello \u2013 rispettivamente responsabili commerciale e tecnico \u2013 abbiamo preso la strada dell\u2019impiantisca sportiva e operiamo su tutto il territorio nazionale. I nostri sono lavori chiavi in mano, non ci appoggiamo a terzi. Ci muoviamo con professionisti del posto e ci occupiamo di tutte le fasi di consulenza, progettazione, realizzazione e manutenzione. Copriamo diverse attivit\u00e0, dal padel alle piste di atletica, senza dimenticare tennis, calcio e naturalmente calcio a 5\u201d.<\/p>\n<p><a href=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio2.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-78051\" src=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio2.jpg\" alt=\"\" width=\"1019\" height=\"713\" srcset=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio2.jpg 1019w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio2-300x210.jpg 300w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio2-768x537.jpg 768w\" sizes=\"(max-width: 1019px) 100vw, 1019px\" \/><\/a><\/p>\n<p>Eccolo qui, l\u2019argomento caldissimo della stagione 2022\/23. Non solo impiantistica: da quest\u2019estate, Giagnorio \u00e8 ufficialmente diventato il massimo dirigente delle biancorosse in Serie A.<br \/>\n\u201cHo conosciuto mister Iessi col quale \u00e8 nato subito un bel feeling e, a seguire, Foti, Martino, Ragno, Anicchiarico, lo staff al completo e la squadra. Oltre ad essere professionisti seri, sono persone per bene e questo mi ha fatto avvicinare tanto, insieme alla condivisione degli stessi valori e della stessa filosofia. Il femminile mi \u00e8 sempre piaciuto: \u00e8 un ambiente pulito e con tanto fairplay. Ora che ci penso \u2013 sorride \u2013 avevo gi\u00e0 avuto una squadra femminile di calcio nel lontano \u201992, ma il campionato non part\u00ec mai a causa di alcune defezioni\u201d.<br \/>\nIl destino ha fatto un giro lunghissimo, durato esattamente 30 anni, ma &#8211; lo scorso 18 settembre &#8211; Giagnorio ha esordito in Serie A rosa nel derby pugliese con lo Statte.<br \/>\n\u201cTanta emozione e un bel po\u2019 di gente sugli spalti per una partita che avrebbe potuto avere anche esito diverso. L\u2019unica pecca, a mio avviso, \u00e8 stata quella di non essere riusciti a chiuderla dopo aver recuperato, anche grazie alla bravura di Margarito che ha sfoderato 3 parate fondamentali. Ci sono state due autoreti che possono capitare, ma sono contento perch\u00e9 la squadra ha giocato: perdere senza giocare sarebbe stato preoccupante, invece \u2013 continua il presidente \u2013 ho visto un gruppo che ha lottato e che ha solo margini di miglioramento. Iessi si \u00e8 calmato solo luned\u00ec sera \u2013 sorride -, ma io sono rimasto sereno: contando che De Souza e Tais Alves avevano appena 3 allenamenti sulle gambe e considerando le occasioni non finalizzate, sono fiducioso di poter raggiungere senza affanni l\u2019obiettivo della salvezza. Se questa volta abbiamo perso tre punti, vuol dire che andremo a cercarli da un\u2019altra parte\u201d.<\/p>\n<p><a href=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio4.jpeg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-large wp-image-78053\" src=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio4-1024x795.jpeg\" alt=\"\" width=\"1000\" height=\"776\" srcset=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio4-1024x795.jpeg 1024w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio4-300x233.jpeg 300w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio4-768x596.jpeg 768w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio4.jpeg 1535w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>Dove? Esattamente a Salsomaggiore Terme, nell\u2019E-R-Arena, sede della seconda giornata di campionato contro la Vip, in diretta su Sky.<br \/>\n\u201c\u00c8 una vetrina importantissima che certifica il boom che ha avuto questo sport. La societ\u00e0, la citt\u00e0 di Molfetta e la Puglia in generale ne trarranno solo beneficio. Il livello \u00e8 ormai altissimo, ma io ho scommesso su questa squadra e sono pronta a vivere questa avventura appassionante, impegnativa e molto stimolante allo stesso tempo. Quando ci sono delle sfide, mi carico e non potrebbe essere altrimenti visto il mio lavoro: per fare impresa oggi in Italia, credimi, ci vuole anche un pizzico di incoscienza\u201d.<br \/>\nE la sfida di quest\u2019anno si chiama, per l\u2019appunto, Femminile Molfetta.<br \/>\n\u201cCredo che si possa fare un campionato dignitoso, cercando di portare a casa pi\u00f9 punti possibili grazie alla buona rosa allestita. Se poi gli avversari avranno dimostrato di essere pi\u00f9 bravi noi, allora gli stringeremo la mano e gli faremo i complimenti. Alla fine, nel calcio, chi vince ha sempre ragione. Il mio compito come presidente? Mi sono posto due obiettivi: sbagliare il meno possibile e aiutare la squadra a crescere nel tempo. Non mi riferisco solo ad un\u2019Under 19, ma alla creazione di un vero e proprio settore giovanile, che avvicini quante pi\u00f9 atlete sia possibile e che costituisca una fonte importante di auto-sostenibilit\u00e0. Il serbatoio deve essere alla base di qualsiasi club che abbia voglia di esserci da qui a molti anni\u201d.<\/p>\n<p><a href=\"https:\/\/www.sportimpiantigicoma.it\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-78016 size-large\" src=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/13123207_967502353357398_7323044439338875844_o-1024x379.jpg\" alt=\"\" width=\"1000\" height=\"370\" srcset=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/13123207_967502353357398_7323044439338875844_o-1024x379.jpg 1024w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/13123207_967502353357398_7323044439338875844_o-300x111.jpg 300w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/13123207_967502353357398_7323044439338875844_o-768x284.jpg 768w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/13123207_967502353357398_7323044439338875844_o-1536x569.jpg 1536w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/13123207_967502353357398_7323044439338875844_o.jpg 1702w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica la sua \u201cprima\u201d da presidente a capo della Femminile Molfetta in Serie A femminile. Un\u2019altra importantissima tappa di un cammino che, per Massimo Giagnorio, \u00e8 stato sempre legatissimo allo sport, sia per quanto riguarda l\u2019impresa che dal 1986 porta avanti insieme al fratello \u2013 la Sport Impianti di San Nicandro al Garganico, fondata da [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":78050,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1083],"tags":[3386,4217,5770],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Massimo Giagnorio e la Femminile Molfetta: &quot;Avventura appassionante&quot;<\/title>\n<meta name=\"description\" content=\"Massimo Giagnorio e il Molfetta: &quot;Avventura appassionante. Voglio sbagliare il meno possibile e far crescere questa squadra nel tempo&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Massimo Giagnorio e la Femminile Molfetta: &quot;Avventura appassionante&quot;\" \/>\n<meta property=\"og:description\" content=\"Massimo Giagnorio e il Molfetta: &quot;Avventura appassionante. Voglio sbagliare il meno possibile e far crescere questa squadra nel tempo&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/\" \/>\n<meta property=\"og:site_name\" content=\"Any Given Sunday\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/anygivensundayit\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-23T08:42:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-23T09:48:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"930\" \/>\n\t<meta property=\"og:image:height\" content=\"463\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anita Ferrante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AGS_Magazine\" \/>\n<meta name=\"twitter:site\" content=\"@AGS_Magazine\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anita Ferrante\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/\"},\"author\":{\"name\":\"Anita Ferrante\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/7fb639a341e46d2b32139b62bca2808a\"},\"headline\":\"Massimo Giagnorio e la Femminile Molfetta: &#8220;Avventura appassionante&#8221;\",\"datePublished\":\"2022-09-23T08:42:05+00:00\",\"dateModified\":\"2022-09-23T09:48:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/\"},\"wordCount\":854,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio1.jpeg\",\"keywords\":[\"Featured\",\"Femminile Molfetta\",\"Massimo Giagnorio\"],\"articleSection\":[\"Serie A\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/\",\"name\":\"Massimo Giagnorio e la Femminile Molfetta: \\\"Avventura appassionante\\\"\",\"isPartOf\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio1.jpeg\",\"datePublished\":\"2022-09-23T08:42:05+00:00\",\"dateModified\":\"2022-09-23T09:48:51+00:00\",\"description\":\"Massimo Giagnorio e il Molfetta: \\\"Avventura appassionante. Voglio sbagliare il meno possibile e far crescere questa squadra nel tempo\\\"\",\"breadcrumb\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#primaryimage\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio1.jpeg\",\"contentUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio1.jpeg\",\"width\":930,\"height\":463,\"caption\":\"giagnorio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.anygivensunday.it\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Massimo Giagnorio e la Femminile Molfetta: &#8220;Avventura appassionante&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#website\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/\",\"name\":\"Any Given Sunday\",\"description\":\"Futsal Femminile, Calcio a 5, eSport, Volley, anygivensunday, ogni maledetta domenica, notizie di sport, storie di sport, Calcio a 5 Femminile, notizie di calcio a 5 femminile\",\"publisher\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.anygivensunday.it\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#organization\",\"name\":\"Any Given Sunday\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2023\/01\/logo_anygivensunday.png\",\"contentUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2023\/01\/logo_anygivensunday.png\",\"width\":200,\"height\":50,\"caption\":\"Any Given Sunday\"},\"image\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/anygivensundayit\/\",\"https:\/\/twitter.com\/AGS_Magazine\",\"https:\/\/www.instagram.com\/anygivensunday_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/7fb639a341e46d2b32139b62bca2808a\",\"name\":\"Anita Ferrante\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/10\/zeudi-150x150.jpg\",\"contentUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/10\/zeudi-150x150.jpg\",\"caption\":\"Anita Ferrante\"},\"url\":\"https:\/\/www.anygivensunday.it\/home\/author\/anita-ferrante\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Massimo Giagnorio e la Femminile Molfetta: \"Avventura appassionante\"","description":"Massimo Giagnorio e il Molfetta: \"Avventura appassionante. Voglio sbagliare il meno possibile e far crescere questa squadra nel tempo\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/","og_locale":"it_IT","og_type":"article","og_title":"Massimo Giagnorio e la Femminile Molfetta: \"Avventura appassionante\"","og_description":"Massimo Giagnorio e il Molfetta: \"Avventura appassionante. Voglio sbagliare il meno possibile e far crescere questa squadra nel tempo\"","og_url":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/","og_site_name":"Any Given Sunday","article_publisher":"https:\/\/www.facebook.com\/anygivensundayit\/","article_published_time":"2022-09-23T08:42:05+00:00","article_modified_time":"2022-09-23T09:48:51+00:00","og_image":[{"width":930,"height":463,"url":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio1.jpeg","type":"image\/jpeg"}],"author":"Anita Ferrante","twitter_card":"summary_large_image","twitter_creator":"@AGS_Magazine","twitter_site":"@AGS_Magazine","twitter_misc":{"Scritto da":"Anita Ferrante","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#article","isPartOf":{"@id":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/"},"author":{"name":"Anita Ferrante","@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/7fb639a341e46d2b32139b62bca2808a"},"headline":"Massimo Giagnorio e la Femminile Molfetta: &#8220;Avventura appassionante&#8221;","datePublished":"2022-09-23T08:42:05+00:00","dateModified":"2022-09-23T09:48:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/"},"wordCount":854,"commentCount":0,"publisher":{"@id":"https:\/\/www.anygivensunday.it\/home\/#organization"},"image":{"@id":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio1.jpeg","keywords":["Featured","Femminile Molfetta","Massimo Giagnorio"],"articleSection":["Serie A"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/","url":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/","name":"Massimo Giagnorio e la Femminile Molfetta: \"Avventura appassionante\"","isPartOf":{"@id":"https:\/\/www.anygivensunday.it\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#primaryimage"},"image":{"@id":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio1.jpeg","datePublished":"2022-09-23T08:42:05+00:00","dateModified":"2022-09-23T09:48:51+00:00","description":"Massimo Giagnorio e il Molfetta: \"Avventura appassionante. Voglio sbagliare il meno possibile e far crescere questa squadra nel tempo\"","breadcrumb":{"@id":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#primaryimage","url":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio1.jpeg","contentUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2022\/09\/giagnorio1.jpeg","width":930,"height":463,"caption":"giagnorio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.anygivensunday.it\/home\/2022\/09\/massimo-giagnorio-e-la-femminile-molfetta-avventura-appassionante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.anygivensunday.it\/home\/"},{"@type":"ListItem","position":2,"name":"Massimo Giagnorio e la Femminile Molfetta: &#8220;Avventura appassionante&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.anygivensunday.it\/home\/#website","url":"https:\/\/www.anygivensunday.it\/home\/","name":"Any Given Sunday","description":"Futsal Femminile, Calcio a 5, eSport, Volley, anygivensunday, ogni maledetta domenica, notizie di sport, storie di sport, Calcio a 5 Femminile, notizie di calcio a 5 femminile","publisher":{"@id":"https:\/\/www.anygivensunday.it\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anygivensunday.it\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.anygivensunday.it\/home\/#organization","name":"Any Given Sunday","url":"https:\/\/www.anygivensunday.it\/home\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2023\/01\/logo_anygivensunday.png","contentUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2023\/01\/logo_anygivensunday.png","width":200,"height":50,"caption":"Any Given Sunday"},"image":{"@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/anygivensundayit\/","https:\/\/twitter.com\/AGS_Magazine","https:\/\/www.instagram.com\/anygivensunday_it"]},{"@type":"Person","@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/7fb639a341e46d2b32139b62bca2808a","name":"Anita Ferrante","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/image\/","url":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/10\/zeudi-150x150.jpg","contentUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/10\/zeudi-150x150.jpg","caption":"Anita Ferrante"},"url":"https:\/\/www.anygivensunday.it\/home\/author\/anita-ferrante\/"}]}},"_links":{"self":[{"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/posts\/78015"}],"collection":[{"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/comments?post=78015"}],"version-history":[{"count":0,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/posts\/78015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/media\/78050"}],"wp:attachment":[{"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/media?parent=78015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/categories?post=78015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/tags?post=78015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}