﻿{"id":74911,"date":"2022-06-27T17:50:45","date_gmt":"2022-06-27T15:50:45","guid":{"rendered":"https:\/\/www.anygivensunday.it\/home\/?p=74911"},"modified":"2022-06-27T17:50:45","modified_gmt":"2022-06-27T15:50:45","slug":"la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei","status":"publish","type":"post","link":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/","title":{"rendered":"La 10 Livorno versione A2: si riparte da capitan Valentina Cei"},"content":{"rendered":"<p><strong>La 10 Futsal Femminile Livorno<\/strong> di nuovo all\u2019opera per proseguire il meraviglioso percorso che dalla C ha portato direttamente in Serie A2, per la prima volta della sua storia. Ecco allora che la societ\u00e0 giallonera annuncia con orgoglio il rinnovo di <strong>Valentina Cei<\/strong>, primo tassello del nuovo scacchiere in definizione. Come dire s\u00ec ad una vacanza tra amici. Tra il capitano e la dirigenza toscana \u00e8 avvenuto tutto in modo molto naturale.<br \/>\n\u201cMi sono trovata bene con tutti e non ho avuto esitazioni a confermare con questo bellissimo gruppo, dalle giocatrici allo staff. L\u2019unica preoccupazione, semmai, \u00e8 quella di non poter essere sempre presente per motivi di lavoro: gli allenamenti sono tanti e gli impegni, che gi\u00e0 di sono fatti sentire l\u2019anno scorso, mi penalizzeranno ancor di pi\u00f9, ma \u2013 per quello che potr\u00e0 \u2013 sono a completa disposizione di mister Vannini. La squadra che verr\u00e0? Mi fido di lui e Borrelli. La base di partenza \u00e8 gi\u00e0 buona e hanno dimostrato di avere ottime conoscenze e visione per completarla nel migliore dei modi\u201d.<br \/>\nPrima volta in A2 non solo per la 10, ma anche per Cei.<br \/>\n\u201cNon so come mi aspetta, \u00e8 una sorpresa. Sicuramente troveremo avversarie molto pi\u00f9 competitive e non ci saranno gare da prendere sottogamba. A prescindere dalla mia fascia \u2013 dice con umilt\u00e0 Valentina \u2013 so che posso contare su giocatrici che hanno gi\u00e0 vissuto la categoria e sono nel calcio a 5 da molti anni che potranno dare una grossa mano a chi \u00e8 alle prime armi, come me. L\u2019anno scorso, dopo l\u2019infortunio, non sono rientrata come avrei voluto, forse c\u2019era troppa adrenalina che non ho saputo gestire, ma poi abbiamo chiuso in casa nostra davanti a tantissima gente che era l\u00ec per sostenerci: voglio ripartire da quella bella sensazione e portarmela dietro fino al prossimo fischio d\u2019inizio\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 10 Futsal Femminile Livorno di nuovo all\u2019opera per proseguire il meraviglioso percorso che dalla C ha portato direttamente in Serie A2, per la prima volta della sua storia. Ecco allora che la societ\u00e0 giallonera annuncia con orgoglio il rinnovo di Valentina Cei, primo tassello del nuovo scacchiere in definizione. Come dire s\u00ec ad una [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":67765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2425],"tags":[3386,5342,5443],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La 10 Livorno versione A2: si riparte da capitan Valentina Cei<\/title>\n<meta name=\"description\" content=\"La 10 Livorno versione A2: si riparte da capitan Valentina Cei\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La 10 Livorno versione A2: si riparte da capitan Valentina Cei\" \/>\n<meta property=\"og:description\" content=\"La 10 Livorno versione A2: si riparte da capitan Valentina Cei\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/\" \/>\n<meta property=\"og:site_name\" content=\"Any Given Sunday\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/anygivensundayit\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-27T15:50:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/12\/cei-ok.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"749\" \/>\n\t<meta property=\"og:image:height\" content=\"538\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anita Ferrante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AGS_Magazine\" \/>\n<meta name=\"twitter:site\" content=\"@AGS_Magazine\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anita Ferrante\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/\"},\"author\":{\"name\":\"Anita Ferrante\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/7fb639a341e46d2b32139b62bca2808a\"},\"headline\":\"La 10 Livorno versione A2: si riparte da capitan Valentina Cei\",\"datePublished\":\"2022-06-27T15:50:45+00:00\",\"dateModified\":\"2022-06-27T15:50:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/\"},\"wordCount\":309,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/12\/cei-ok.jpeg\",\"keywords\":[\"Featured\",\"La 10 Livorno Futsal Femminile\",\"valentina cei\"],\"articleSection\":[\"Serie C\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/\",\"name\":\"La 10 Livorno versione A2: si riparte da capitan Valentina Cei\",\"isPartOf\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/12\/cei-ok.jpeg\",\"datePublished\":\"2022-06-27T15:50:45+00:00\",\"dateModified\":\"2022-06-27T15:50:45+00:00\",\"description\":\"La 10 Livorno versione A2: si riparte da capitan Valentina Cei\",\"breadcrumb\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#primaryimage\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/12\/cei-ok.jpeg\",\"contentUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/12\/cei-ok.jpeg\",\"width\":749,\"height\":538,\"caption\":\"Valentina Cei\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.anygivensunday.it\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La 10 Livorno versione A2: si riparte da capitan Valentina Cei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#website\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/\",\"name\":\"Any Given Sunday\",\"description\":\"Futsal Femminile, Calcio a 5, eSport, Volley, anygivensunday, ogni maledetta domenica, notizie di sport, storie di sport, Calcio a 5 Femminile, notizie di calcio a 5 femminile\",\"publisher\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.anygivensunday.it\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#organization\",\"name\":\"Any Given Sunday\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2023\/01\/logo_anygivensunday.png\",\"contentUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2023\/01\/logo_anygivensunday.png\",\"width\":200,\"height\":50,\"caption\":\"Any Given Sunday\"},\"image\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/anygivensundayit\/\",\"https:\/\/twitter.com\/AGS_Magazine\",\"https:\/\/www.instagram.com\/anygivensunday_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/7fb639a341e46d2b32139b62bca2808a\",\"name\":\"Anita Ferrante\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/10\/zeudi-150x150.jpg\",\"contentUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/10\/zeudi-150x150.jpg\",\"caption\":\"Anita Ferrante\"},\"url\":\"https:\/\/www.anygivensunday.it\/home\/author\/anita-ferrante\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La 10 Livorno versione A2: si riparte da capitan Valentina Cei","description":"La 10 Livorno versione A2: si riparte da capitan Valentina Cei","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/","og_locale":"it_IT","og_type":"article","og_title":"La 10 Livorno versione A2: si riparte da capitan Valentina Cei","og_description":"La 10 Livorno versione A2: si riparte da capitan Valentina Cei","og_url":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/","og_site_name":"Any Given Sunday","article_publisher":"https:\/\/www.facebook.com\/anygivensundayit\/","article_published_time":"2022-06-27T15:50:45+00:00","og_image":[{"width":749,"height":538,"url":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/12\/cei-ok.jpeg","type":"image\/jpeg"}],"author":"Anita Ferrante","twitter_card":"summary_large_image","twitter_creator":"@AGS_Magazine","twitter_site":"@AGS_Magazine","twitter_misc":{"Scritto da":"Anita Ferrante","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#article","isPartOf":{"@id":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/"},"author":{"name":"Anita Ferrante","@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/7fb639a341e46d2b32139b62bca2808a"},"headline":"La 10 Livorno versione A2: si riparte da capitan Valentina Cei","datePublished":"2022-06-27T15:50:45+00:00","dateModified":"2022-06-27T15:50:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/"},"wordCount":309,"commentCount":0,"publisher":{"@id":"https:\/\/www.anygivensunday.it\/home\/#organization"},"image":{"@id":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/12\/cei-ok.jpeg","keywords":["Featured","La 10 Livorno Futsal Femminile","valentina cei"],"articleSection":["Serie C"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/","url":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/","name":"La 10 Livorno versione A2: si riparte da capitan Valentina Cei","isPartOf":{"@id":"https:\/\/www.anygivensunday.it\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#primaryimage"},"image":{"@id":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/12\/cei-ok.jpeg","datePublished":"2022-06-27T15:50:45+00:00","dateModified":"2022-06-27T15:50:45+00:00","description":"La 10 Livorno versione A2: si riparte da capitan Valentina Cei","breadcrumb":{"@id":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#primaryimage","url":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/12\/cei-ok.jpeg","contentUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/12\/cei-ok.jpeg","width":749,"height":538,"caption":"Valentina Cei"},{"@type":"BreadcrumbList","@id":"https:\/\/www.anygivensunday.it\/home\/2022\/06\/la-10-livorno-versione-a2-si-riparte-da-capitan-valentina-cei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.anygivensunday.it\/home\/"},{"@type":"ListItem","position":2,"name":"La 10 Livorno versione A2: si riparte da capitan Valentina Cei"}]},{"@type":"WebSite","@id":"https:\/\/www.anygivensunday.it\/home\/#website","url":"https:\/\/www.anygivensunday.it\/home\/","name":"Any Given Sunday","description":"Futsal Femminile, Calcio a 5, eSport, Volley, anygivensunday, ogni maledetta domenica, notizie di sport, storie di sport, Calcio a 5 Femminile, notizie di calcio a 5 femminile","publisher":{"@id":"https:\/\/www.anygivensunday.it\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anygivensunday.it\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.anygivensunday.it\/home\/#organization","name":"Any Given Sunday","url":"https:\/\/www.anygivensunday.it\/home\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2023\/01\/logo_anygivensunday.png","contentUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2023\/01\/logo_anygivensunday.png","width":200,"height":50,"caption":"Any Given Sunday"},"image":{"@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/anygivensundayit\/","https:\/\/twitter.com\/AGS_Magazine","https:\/\/www.instagram.com\/anygivensunday_it"]},{"@type":"Person","@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/7fb639a341e46d2b32139b62bca2808a","name":"Anita Ferrante","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/image\/","url":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/10\/zeudi-150x150.jpg","contentUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/10\/zeudi-150x150.jpg","caption":"Anita Ferrante"},"url":"https:\/\/www.anygivensunday.it\/home\/author\/anita-ferrante\/"}]}},"_links":{"self":[{"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/posts\/74911"}],"collection":[{"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/comments?post=74911"}],"version-history":[{"count":0,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/posts\/74911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/media\/67765"}],"wp:attachment":[{"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/media?parent=74911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/categories?post=74911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/tags?post=74911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}