﻿{"id":45525,"date":"2019-11-07T10:34:06","date_gmt":"2019-11-07T09:34:06","guid":{"rendered":"https:\/\/www.anygivensunday.it\/home\/?p=45525"},"modified":"2019-11-07T10:57:13","modified_gmt":"2019-11-07T09:57:13","slug":"deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica","status":"publish","type":"post","link":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/","title":{"rendered":"Deborah Pieroni, una campionessa di Judo al servizio della Dorica"},"content":{"rendered":"<p>Una campionessa di Judo al servizio della <strong>Dorica Torrette<\/strong>. Di chi stiamo parlando? Naturalmente di <strong>Deborah Pieroni<\/strong>, laterale classe \u201989 con un passato \u2013 e che passato \u2013 nelle arti marziali. Ora le sue gare iniziano sempre con il suono della sirena dentro qualche palazzetto, ma fino ai 20 anni \u00e8 stata la voce di un arbitro a farla scattare in guardia al comando di \u201cHajime\u201d (\u201ccominciate\u201d). Un bronzo nel 2002 ad Alassio e un oro nel 2003 a Pistoia i riconoscimenti nazionali pi\u00f9 importanti della cintura nera dorica, arrivata ai massimi livelli della categoria (esordienti kg.63) con tanta dedizione.<br \/>\n<em>\u201cHo frequentato il dojo (la palestra) tutti i giorni per 8 anni: 5 allenamenti a settimana, pi\u00f9 la gara della domenica. Ho affrontato competizioni in tutta Italia, tiravo fuori tutta la grinta che avevo e questo mi aiutava a vincere\u201d<\/em>.<br \/>\nUna famiglia di combattenti: il fratello, Diego, \u00e8 infatti un ex pugile, ora insegnante di pugilato, e da un po\u2019 di tempo anche Martina, figlia di Deborah, ha iniziato a cimentarsi con le varie prese sul tatami.<br \/>\n<em>\u201cE\u2019 stata una sua decisione, io avrei voluto che iniziasse pi\u00f9 tardi perch\u00e9 il Judo \u00e8 prima di tutto disciplina e richiede forse troppa fatica per una bambina di 7 anni, ma vedo che ci mette tanta precisione e volont\u00e0. Se una mossa non esce come vorrebbe, la riprova tantissime volte. E devo dire che in questo \u00e8 testarda come me\u201d<\/em>, scherza.<\/p>\n<div id=\"attachment_45531\" style=\"width: 715px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/pieroni.jpeg\"><img aria-describedby=\"caption-attachment-45531\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-45531\" src=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/pieroni.jpeg\" alt=\"\" width=\"705\" height=\"693\" srcset=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/pieroni.jpeg 705w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/pieroni-300x295.jpeg 300w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/pieroni-80x80.jpeg 80w\" sizes=\"(max-width: 705px) 100vw, 705px\" \/><\/a><p id=\"caption-attachment-45531\" class=\"wp-caption-text\">Pieroni con il maestro di vita Giancarlo Gironelli<\/p><\/div>\n<p>Nonostante le soddisfazioni ottenute, Deborah si vede costretta a tralasciare il Judo quando inizia a lavorare e il suo impegno non pu\u00f2 pi\u00f9 essere costante: \u00e8 in quel periodo che la passione per il calcio che l\u2019ha accompagnata fin da piccola inizia a farsi sentire ancora pi\u00f9 forte. In zona non ci sono tante squadre femminili, ma Pieroni si guarda intorno e inizia nel Real Offagna, stagione per\u00f2 condizionata da un brutto infortunio alla mano che la ferma per 6 mesi e l\u2019allontana definitivamente dalle gare di Judo (ma non dagli allenamenti). L\u2019anno successivo riprende col Real Offagna, poi 5 anni a Camerano, uno alla GLS Dorica in C ed infine la chiamata di Mirco Massa per l\u2019A2.<br \/>\n<em>\u201cPer me che mi sono un po\u2019 persa le basi formative di questo sport avendo iniziato tardi, \u00e8 una sfida difficile e affascinante allo stesso tempo. Anche se a livello tecnico il campionato \u00e8 duro, qui mi trovo molto bene: la dirigenza \u00e8 sempre presente e il mister tiene tanto al progetto, mi dispiace per gli ultimi risultati ottenuti perch\u00e9 so che questa squadra potrebbe dare molto di pi\u00f9. A volte cerchiamo troppo la giocata individuale, quando basterebbe giocare un po\u2019 pi\u00f9 di squadra per riuscire a dire la nostra\u201d<\/em>.<\/p>\n<p><a href=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19.jpeg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-large wp-image-45585\" src=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-1024x682.jpeg\" alt=\"\" width=\"1000\" height=\"666\" srcset=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19.jpeg 1024w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-300x200.jpeg 300w, https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-768x512.jpeg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>Un ko inaspettato con il Foligno e un altro con il Citt\u00e0 di Capena, in cui si \u00e8 vista una Dorica dai due volti.<br \/>\n<em>\u201cNel primo tempo ci siamo difese bene: magari in fase offensiva ci siamo viste poco, una carenza che ci portiamo dietro da inizio anno, ma abbiamo tenuto testa alle avversarie; nel secondo \u2013 invece \u2013 ci \u00e8 mancata la giusta intensit\u00e0\u201d<\/em>.<br \/>\nCali di tensione che saranno assolutamente vietati nella trasferta di Roma contro la temibile Sabina Lazio Calcetto.<br \/>\n<em>\u201cDobbiamo andare l\u00ec e strappare quei punti che ci servono per la classifica e per noi stesse: sulla carta abbiamo nomi importanti quanto i loro, ma \u2013 oltre alla tecnica \u2013 serve tanta grinta, perch\u00e9 fino ad oggi non abbiamo mai messo il 100% in campo. A tal proposito<\/em> \u2013 chiude Pieroni \u2013 <em>vorrei fare un plauso a Pezzolla: domenica scorsa \u00e8 stata molto brava a trascinare la squadra sin dal riscaldamento. Ci ha tenute sveglie e ci ha incitate, dando una sicurezza in pi\u00f9 a chi \u2013 come me &#8211; riconosce di avere dei limiti e cerca punti di riferimento. Ci sono giocatrici che possono dare un valore aggiunto e dovrebbero dimostrarlo in ogni partita: vederla cos\u00ec carica mi ha fatto bene e spero che questo atteggiamento possa essere una spinta in pi\u00f9 per tutta la squadra\u201d<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una campionessa di Judo al servizio della Dorica Torrette. Di chi stiamo parlando? Naturalmente di Deborah Pieroni, laterale classe \u201989 con un passato \u2013 e che passato \u2013 nelle arti marziali. Ora le sue gare iniziano sempre con il suono della sirena dentro qualche palazzetto, ma fino ai 20 anni \u00e8 stata la voce di [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":45584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2220],"tags":[4485,2792,3386],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deborah Pieroni, una campionessa di Judo al servizio della Dorica<\/title>\n<meta name=\"description\" content=\"Deborah Pieroni, una campionessa di Judo al servizio della Dorica Torrette\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deborah Pieroni, una campionessa di Judo al servizio della Dorica\" \/>\n<meta property=\"og:description\" content=\"Deborah Pieroni, una campionessa di Judo al servizio della Dorica Torrette\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/\" \/>\n<meta property=\"og:site_name\" content=\"Any Given Sunday\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/anygivensundayit\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-07T09:34:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-07T09:57:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Silvia Vinditti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AGS_Magazine\" \/>\n<meta name=\"twitter:site\" content=\"@AGS_Magazine\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Silvia Vinditti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/\"},\"author\":{\"name\":\"Silvia Vinditti\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/772f2bedb64470b6cb1113934e7031b0\"},\"headline\":\"Deborah Pieroni, una campionessa di Judo al servizio della Dorica\",\"datePublished\":\"2019-11-07T09:34:06+00:00\",\"dateModified\":\"2019-11-07T09:57:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/\"},\"wordCount\":666,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-1.jpeg\",\"keywords\":[\"deborah pieroni\",\"dorica torrette\",\"Featured\"],\"articleSection\":[\"Serie B\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/\",\"name\":\"Deborah Pieroni, una campionessa di Judo al servizio della Dorica\",\"isPartOf\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-1.jpeg\",\"datePublished\":\"2019-11-07T09:34:06+00:00\",\"dateModified\":\"2019-11-07T09:57:13+00:00\",\"description\":\"Deborah Pieroni, una campionessa di Judo al servizio della Dorica Torrette\",\"breadcrumb\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#primaryimage\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-1.jpeg\",\"contentUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-1.jpeg\",\"width\":1024,\"height\":682,\"caption\":\"Deborah Pieroni\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.anygivensunday.it\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deborah Pieroni, una campionessa di Judo al servizio della Dorica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#website\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/\",\"name\":\"Any Given Sunday\",\"description\":\"Futsal Femminile, Calcio a 5, eSport, Volley, anygivensunday, ogni maledetta domenica, notizie di sport, storie di sport, Calcio a 5 Femminile, notizie di calcio a 5 femminile\",\"publisher\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.anygivensunday.it\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#organization\",\"name\":\"Any Given Sunday\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2023\/01\/logo_anygivensunday.png\",\"contentUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2023\/01\/logo_anygivensunday.png\",\"width\":200,\"height\":50,\"caption\":\"Any Given Sunday\"},\"image\":{\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/anygivensundayit\/\",\"https:\/\/twitter.com\/AGS_Magazine\",\"https:\/\/www.instagram.com\/anygivensunday_it\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/772f2bedb64470b6cb1113934e7031b0\",\"name\":\"Silvia Vinditti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/10\/profilo-150x150.jpg\",\"contentUrl\":\"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/10\/profilo-150x150.jpg\",\"caption\":\"Silvia Vinditti\"},\"description\":\"Silvia all'anagrafe, Fulvia per gli amici, la rossa da che mondo \u00e8 mondo. Tre decenni spesi a contraddirmi. Adesso, per\u00f2, siamo tutti d'accordo.\",\"url\":\"https:\/\/www.anygivensunday.it\/home\/author\/silvia-vinditti\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deborah Pieroni, una campionessa di Judo al servizio della Dorica","description":"Deborah Pieroni, una campionessa di Judo al servizio della Dorica Torrette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/","og_locale":"it_IT","og_type":"article","og_title":"Deborah Pieroni, una campionessa di Judo al servizio della Dorica","og_description":"Deborah Pieroni, una campionessa di Judo al servizio della Dorica Torrette","og_url":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/","og_site_name":"Any Given Sunday","article_publisher":"https:\/\/www.facebook.com\/anygivensundayit\/","article_published_time":"2019-11-07T09:34:06+00:00","article_modified_time":"2019-11-07T09:57:13+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-1.jpeg","type":"image\/jpeg"}],"author":"Silvia Vinditti","twitter_card":"summary_large_image","twitter_creator":"@AGS_Magazine","twitter_site":"@AGS_Magazine","twitter_misc":{"Scritto da":"Silvia Vinditti","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#article","isPartOf":{"@id":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/"},"author":{"name":"Silvia Vinditti","@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/772f2bedb64470b6cb1113934e7031b0"},"headline":"Deborah Pieroni, una campionessa di Judo al servizio della Dorica","datePublished":"2019-11-07T09:34:06+00:00","dateModified":"2019-11-07T09:57:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/"},"wordCount":666,"commentCount":0,"publisher":{"@id":"https:\/\/www.anygivensunday.it\/home\/#organization"},"image":{"@id":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-1.jpeg","keywords":["deborah pieroni","dorica torrette","Featured"],"articleSection":["Serie B"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/","url":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/","name":"Deborah Pieroni, una campionessa di Judo al servizio della Dorica","isPartOf":{"@id":"https:\/\/www.anygivensunday.it\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#primaryimage"},"image":{"@id":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-1.jpeg","datePublished":"2019-11-07T09:34:06+00:00","dateModified":"2019-11-07T09:57:13+00:00","description":"Deborah Pieroni, una campionessa di Judo al servizio della Dorica Torrette","breadcrumb":{"@id":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#primaryimage","url":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-1.jpeg","contentUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2019\/11\/WhatsApp-Image-2019-11-06-at-19.33.19-1.jpeg","width":1024,"height":682,"caption":"Deborah Pieroni"},{"@type":"BreadcrumbList","@id":"https:\/\/www.anygivensunday.it\/home\/2019\/11\/deborah-pieroni-una-campionessa-di-judo-al-servizio-della-dorica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.anygivensunday.it\/home\/"},{"@type":"ListItem","position":2,"name":"Deborah Pieroni, una campionessa di Judo al servizio della Dorica"}]},{"@type":"WebSite","@id":"https:\/\/www.anygivensunday.it\/home\/#website","url":"https:\/\/www.anygivensunday.it\/home\/","name":"Any Given Sunday","description":"Futsal Femminile, Calcio a 5, eSport, Volley, anygivensunday, ogni maledetta domenica, notizie di sport, storie di sport, Calcio a 5 Femminile, notizie di calcio a 5 femminile","publisher":{"@id":"https:\/\/www.anygivensunday.it\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anygivensunday.it\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.anygivensunday.it\/home\/#organization","name":"Any Given Sunday","url":"https:\/\/www.anygivensunday.it\/home\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2023\/01\/logo_anygivensunday.png","contentUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2023\/01\/logo_anygivensunday.png","width":200,"height":50,"caption":"Any Given Sunday"},"image":{"@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/anygivensundayit\/","https:\/\/twitter.com\/AGS_Magazine","https:\/\/www.instagram.com\/anygivensunday_it"]},{"@type":"Person","@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/772f2bedb64470b6cb1113934e7031b0","name":"Silvia Vinditti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anygivensunday.it\/home\/#\/schema\/person\/image\/","url":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/10\/profilo-150x150.jpg","contentUrl":"https:\/\/www.anygivensunday.it\/home\/wp-content\/uploads\/2021\/10\/profilo-150x150.jpg","caption":"Silvia Vinditti"},"description":"Silvia all'anagrafe, Fulvia per gli amici, la rossa da che mondo \u00e8 mondo. Tre decenni spesi a contraddirmi. Adesso, per\u00f2, siamo tutti d'accordo.","url":"https:\/\/www.anygivensunday.it\/home\/author\/silvia-vinditti\/"}]}},"_links":{"self":[{"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/posts\/45525"}],"collection":[{"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/comments?post=45525"}],"version-history":[{"count":0,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/posts\/45525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/media\/45584"}],"wp:attachment":[{"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/media?parent=45525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/categories?post=45525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.anygivensunday.it\/home\/wp-json\/wp\/v2\/tags?post=45525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}